{"id":1103,"count":1,"description":"","link":"https:\/\/amxim.com\/es\/etiqueta\/asociacion-a-largo-plazo\/","name":"Asociaci\u00f3n a largo plazo","slug":"asociacion-a-largo-plazo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/posts?tags=1103"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}