{"id":252,"count":2,"description":"","link":"https:\/\/amxim.com\/es\/etiqueta\/glicerina-vegetal\/","name":"Glicerina vegetal","slug":"glicerina-vegetal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/posts?tags=252"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}