{"id":261,"count":1,"description":"","link":"https:\/\/amxim.com\/es\/etiqueta\/tasa-de-absorcion\/","name":"Tasa de absorci\u00f3n","slug":"tasa-de-absorcion","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/es\/wp-json\/wp\/v2\/posts?tags=261"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}