{"id":12514,"date":"2024-09-12T08:51:36","date_gmt":"2024-09-12T08:51:36","guid":{"rendered":"https:\/\/amxim.com\/?p=12514"},"modified":"2026-04-23T07:10:37","modified_gmt":"2026-04-23T07:10:37","slug":"guide-rapide-sur-la-conformite-tpd-pour-les-marques-de-vape","status":"publish","type":"post","link":"https:\/\/amxim.com\/fr\/guide-rapide-sur-la-conformite-tpd-pour-les-marques-de-vape\/","title":{"rendered":"Guide rapide sur la conformit\u00e9 TPD pour les marques de vapotage"},"content":{"rendered":"<p>Si vous souhaitez vendre des cigarettes \u00e9lectroniques dans l&#039;Union europ\u00e9enne, vous devez respecter la Directive sur les produits du tabac (DPT). Ce guide explique la conformit\u00e9 \u00e0 la DPT et comment AMXIM, fabricant OEM de cigarettes \u00e9lectroniques de confiance en Chine, aide votre entreprise \u00e0 rester en conformit\u00e9.<\/p>\n<h2 id=\"section1\">Qu&#039;est-ce que le TPD ?<\/h2>\n<p>La TPD est un r\u00e8glement de l&#039;UE qui contr\u00f4le la vente, la pr\u00e9sentation et la fabrication des produits du tabac et des cigarettes \u00e9lectroniques. Son objectif est de prot\u00e9ger la sant\u00e9 publique et de garantir la s\u00e9curit\u00e9 de tous les produits.<\/p>\n<h2 id=\"section2\">Exigences cl\u00e9s de la DPT<\/h2>\n<p>Pour vendre des produits de vapotage dans l&#039;UE, voici quelques r\u00e8gles \u00e0 suivre :<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>E-liquid must not contain more than 20mg\/ml of nicotine<\/li>\n<li>Tanks and pods must be less than 2ml in capacity<\/li>\n<li>Bottles for refill e-liquids must be no more than 10ml<\/li>\n<li>Packaging must include warnings and safety information<\/li>\n<li>Products must be notified to the EU six months before they hit the market<\/li>\n<li>Manufacturers must submit test reports and ingredients<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"section3\">Pourquoi choisir AMXIM pour les produits conformes \u00e0 la TPD\u00a0?<\/h2>\n<p>Chez AMXIM, nous sommes bien plus qu&#039;un simple fabricant de vapoteuses en Chine. Nous proposons des services OEM\/ODM de vapoteuses sur mesure, conformes aux normes europ\u00e9ennes. Voici comment nous soutenons votre marque\u00a0:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Syst\u00e8mes de dosettes et produits jetables conformes \u00e0 la TPD<\/li>\n<li>Full support with testing, documentation, and notification<\/li>\n<li>Help with custom design and flavor development<\/li>\n<li>Faible quantit\u00e9 minimum de commande (MOQ)<\/li>\n<li>Fast delivery and strict quality control<\/li>\n<li>Experience working with EU clients and regulations<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"section4\">Partenaire OEM de confiance pour les vapoteurs<\/h2>\n<p>AMXIM est une usine de cigarettes \u00e9lectroniques fiable en Chine, avec une client\u00e8le internationale. Que vous ayez besoin de services de fourniture de cigarettes \u00e9lectroniques jetables ou d&#039;une solution compl\u00e8te de fabrication de cigarettes \u00e9lectroniques OEM, nous sommes l\u00e0 pour vous aider. Tous nos produits sont certifi\u00e9s ISO et test\u00e9s pour r\u00e9pondre aux normes internationales telles que TPD, FCC, CE, RoHS et UKCA.<\/p>\n<h2 id=\"section5\">D\u00e9marrer avec AMXIM<\/h2>\n<p>Vous souhaitez lancer votre propre marque de vape conforme \u00e0 la directive TPD\u00a0? Collaborez avec AMXIM, un fabricant OEM de vape reconnu en Chine. De la conception \u00e0 la livraison, nous vous accompagnons \u00e0 chaque \u00e9tape.<\/p>\n<p>\ud83d\udc49 En savoir plus sur <a href=\"https:\/\/amxim.com\/fr\/\" rel=\"dofollow\"> <b>www.amxim.com<\/b> <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>If you want to sell e-cigarettes in the European Union, you must follow the Tobacco Products Directive (TPD). This guide<\/p>","protected":false},"author":2,"featured_media":12515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[804,753,761,751,783,762],"class_list":["post-12514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-custom-vape-oem-odm-2","tag-disposable-vape-supplier","tag-e-cigarette-factory-china","tag-tobacco-products-directive","tag-tpd-compliance","tag-vape-oem-manufacturer"],"_links":{"self":[{"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/posts\/12514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/comments?post=12514"}],"version-history":[{"count":2,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/posts\/12514\/revisions"}],"predecessor-version":[{"id":14086,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/posts\/12514\/revisions\/14086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/media\/12515"}],"wp:attachment":[{"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/media?parent=12514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/categories?post=12514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amxim.com\/fr\/wp-json\/wp\/v2\/tags?post=12514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}