{"id":345,"count":1,"description":"","link":"https:\/\/amxim.com\/it\/etichetta\/sapore-di-mix-di-frutti-di-bosco\/","name":"Gusto Mix di Frutti di Bosco","slug":"sapore-di-mix-di-frutti-di-bosco","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/tags\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/posts?tags=345"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}