{"id":843,"count":1,"description":"","link":"https:\/\/amxim.com\/it\/etichetta\/imballaggio-per-vaporizzatori\/","name":"Imballaggio per vaporizzatori","slug":"imballaggio-per-vaporizzatori","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/tags\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/it\/wp-json\/wp\/v2\/posts?tags=843"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}