{"id":1105,"count":1,"description":"","link":"https:\/\/amxim.com\/ko\/%ea%bc%ac%eb%a6%ac%ed%91%9c\/%eb%b0%95%ec%8a%a4-%eb%aa%a8%eb%93%9c\/","name":"\ubc15\uc2a4 \ubaa8\ub4dc","slug":"%eb%b0%95%ec%8a%a4-%eb%aa%a8%eb%93%9c","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags\/1105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/posts?tags=1105"}],"curies":[{"name":"\uc6cc\ub4dc\ud504\ub808\uc2a4","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}