{"id":719,"count":1,"description":"","link":"https:\/\/amxim.com\/ko\/%ea%bc%ac%eb%a6%ac%ed%91%9c\/%ec%a4%91%ea%b5%ad-%eb%b9%a0%eb%a5%b8-%eb%b2%a0%ec%9d%b4%ed%94%84-%eb%b0%b0%eb%8b%ac\/","name":"\uc911\uad6d \ube60\ub978 \ubca0\uc774\ud504 \ubc30\uc1a1","slug":"%ec%a4%91%ea%b5%ad-%eb%b9%a0%eb%a5%b8-%eb%b2%a0%ec%9d%b4%ed%94%84-%eb%b0%b0%eb%8b%ac","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/posts?tags=719"}],"curies":[{"name":"\uc6cc\ub4dc\ud504\ub808\uc2a4","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}