{"id":985,"count":1,"description":"","link":"https:\/\/amxim.com\/ko\/%ea%bc%ac%eb%a6%ac%ed%91%9c\/%eb%b2%a0%ec%9d%b4%ed%94%84-%ea%b3%b5%ea%b8%b0-%ed%9d%90%eb%a6%84-%ec%a1%b0%ec%a0%88-%eb%b0%a9%eb%b2%95\/","name":"\ubca0\uc774\ud504 \uacf5\uae30 \ud750\ub984 \uc870\uc808 \ubc29\ubc95","slug":"%eb%b2%a0%ec%9d%b4%ed%94%84-%ea%b3%b5%ea%b8%b0-%ed%9d%90%eb%a6%84-%ec%a1%b0%ec%a0%88-%eb%b0%a9%eb%b2%95","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags\/985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/amxim.com\/ko\/wp-json\/wp\/v2\/posts?tags=985"}],"curies":[{"name":"\uc6cc\ub4dc\ud504\ub808\uc2a4","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}